{"id":21806,"date":"2024-04-02T18:26:00","date_gmt":"2024-04-02T18:26:00","guid":{"rendered":"https:\/\/www.laseyta.com\/?post_type=product&#038;p=21806"},"modified":"2024-07-28T13:40:33","modified_gmt":"2024-07-28T13:40:33","slug":"silver-mini-stud-earing-zircon-drop-sapphire","status":"publish","type":"product","link":"https:\/\/www.laseyta.com\/es\/producto\/plata-mini-tacon-oreja-circon-gota-zafiro\/","title":{"rendered":"Mini Pendientes de plata-Zirconio \/ zafiro"},"content":{"rendered":"<p>Material: Plata de ley 925.<br \/>\nDebido a la naturaleza artesanal del producto, el peso puede variar en (+-0,10).<br \/>\nCuidado del producto: No se empa\u00f1a siempre que evites el contacto con lej\u00eda, alcohol, agua, perfume y sustancias similares.<\/p>","protected":false},"excerpt":{"rendered":"<p>Material: Plata de ley 925. Debido a la naturaleza artesanal del producto, el peso puede variar en (+-0,10). Cuidado del producto: No se empa\u00f1ar\u00e1 siempre que evite el contacto con lej\u00eda, alcohol, agua, perfume y sustancias similares.<\/p>","protected":false},"featured_media":21384,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[434],"product_tag":[],"class_list":{"0":"post-21806","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-laseyta","7":"product_cat-earrings-women-silver","9":"first","10":"outofstock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/product\/21806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/comments?post=21806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/media\/21384"}],"wp:attachment":[{"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/media?parent=21806"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/product_cat?post=21806"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.laseyta.com\/es\/wp-json\/wp\/v2\/product_tag?post=21806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}